{"id":54587,"date":"2024-03-15T10:30:00","date_gmt":"2024-03-15T09:30:00","guid":{"rendered":"http:\/\/turismevalles.com.mialias.net\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/"},"modified":"2024-03-15T10:31:30","modified_gmt":"2024-03-15T09:31:30","slug":"festa-dels-3-tombs-a-les-franqueses-del-valles","status":"publish","type":"mec-events","link":"https:\/\/turismevalles.com\/es\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/","title":{"rendered":"Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s"},"content":{"rendered":"<div class=\"h1-cont\">\n<h1>Fiesta de San Antonio. Tres Tombs<\/h1>\n<\/div>\n<div class=\"inner-padding\">\n<div class=\"brcm-cms-flash-messages\"><\/div>\n<div class=\"brcm-calendar-module\">\n<div class=\"brcm-event-detail\">\n<div class=\"brcm-event-detail-column-left\">\n<p>D\u00eda y hora:\u00a0domingo 07\/04\/2024<\/p>\n<p>9.30 h\u00a0Almorzar de arrieros y concentraci\u00f3n de los participantes en el paseo Tagamanent.<\/p>\n<p>11 h\u00a0Oficio religioso a la Parroquia de Santa Eul\u00e0lia de M\u00e9rida de Rodillo de Abajo.<\/p>\n<p>11.30 h\u00a0Formaci\u00f3n del desfile.<\/p>\n<p>12.00 h Bendici\u00f3n de los animales en la plaza de la Iglesia (c. Santo Pon\u00e7 \u2013 Av Santa Eul\u00e0lia) e inicio del Pase de los Tres Tumbos.<\/p>\n<p>13.45 h Desfilada individual de todos los participantes en el desfile y entrega de obsequios a los participantes. Degustaci\u00f3n de borregos y vino dulce.<\/p>\n<p>Info:\u00a0<a href=\"https:\/\/www.lesfranqueses.cat\/actualitat\/agenda\/2024\/04\/07\/festa-de-sant-antoni-tres-tombs\">https:\/\/www.lesfranqueses.cat\/actualitat\/agenda\/2024\/04\/07\/festa-de-sant-antoni-tres-tombs<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fiesta de San Antonio. Tres Tombs D\u00eda y hora:\u00a0domingo 07\/04\/2024 9.30 h\u00a0Almorzar de arrieros y concentraci\u00f3n de los participantes en el paseo Tagamanent. 11 h\u00a0Oficio &#8230; <a title=\"Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s\" class=\"read-more\" href=\"https:\/\/turismevalles.com\/es\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/\" aria-label=\"M\u00e1s en Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s\">Veure m\u00e9s<\/a><\/p>\n","protected":false},"author":5,"featured_media":54407,"comment_status":"open","ping_status":"closed","template":"","tags":[2204],"poblacions":[903],"mec_category":[970,929],"class_list":["post-54587","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-tres-tombs-es","poblacions-les-franqueses-del-valles-es","mec_category-activitats-en-familia-es","mec_category-cultura-es","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s - Turisme Vall\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s - Turisme Vall\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Fiesta de San Antonio. Tres Tombs D\u00eda y hora:\u00a0domingo 07\/04\/2024 9.30 h\u00a0Almorzar de arrieros y concentraci\u00f3n de los participantes en el paseo Tagamanent. 11 h\u00a0Oficio ... Veure m\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/\" \/>\n<meta property=\"og:site_name\" content=\"Turisme Vall\u00e8s\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-15T09:31:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"116\" \/>\n\t<meta property=\"og:image:height\" content=\"121\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/\",\"url\":\"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/\",\"name\":\"Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s - Turisme Vall\u00e8s\",\"isPartOf\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg\",\"datePublished\":\"2024-03-15T09:30:00+00:00\",\"dateModified\":\"2024-03-15T09:31:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/#primaryimage\",\"url\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg\",\"contentUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg\",\"width\":116,\"height\":121},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/turismevalles.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\/\/turismevalles.com\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turismevalles.com\/en\/#website\",\"url\":\"https:\/\/turismevalles.com\/en\/\",\"name\":\"Turisme Vall\u00e8s\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turismevalles.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/turismevalles.com\/en\/#organization\",\"name\":\"Turisme Vall\u00e8s\",\"url\":\"https:\/\/turismevalles.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png\",\"contentUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png\",\"width\":314,\"height\":85,\"caption\":\"Turisme Vall\u00e8s\"},\"image\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s - Turisme Vall\u00e8s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/","og_locale":"es_ES","og_type":"article","og_title":"Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s - Turisme Vall\u00e8s","og_description":"Fiesta de San Antonio. Tres Tombs D\u00eda y hora:\u00a0domingo 07\/04\/2024 9.30 h\u00a0Almorzar de arrieros y concentraci\u00f3n de los participantes en el paseo Tagamanent. 11 h\u00a0Oficio ... Veure m\u00e9s","og_url":"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/","og_site_name":"Turisme Vall\u00e8s","article_modified_time":"2024-03-15T09:31:30+00:00","og_image":[{"width":116,"height":121,"url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/","url":"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/","name":"Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s - Turisme Vall\u00e8s","isPartOf":{"@id":"https:\/\/turismevalles.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/#primaryimage"},"image":{"@id":"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/#primaryimage"},"thumbnailUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg","datePublished":"2024-03-15T09:30:00+00:00","dateModified":"2024-03-15T09:31:30+00:00","breadcrumb":{"@id":"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/#primaryimage","url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg","contentUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg","width":116,"height":121},{"@type":"BreadcrumbList","@id":"https:\/\/turismevalles.com\/events\/festa-dels-3-tombs-a-les-franqueses-del-valles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/turismevalles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/turismevalles.com\/events\/"},{"@type":"ListItem","position":3,"name":"Fiesta de los 3 Tombs en Les Franqueses del Vall\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/turismevalles.com\/en\/#website","url":"https:\/\/turismevalles.com\/en\/","name":"Turisme Vall\u00e8s","description":"","publisher":{"@id":"https:\/\/turismevalles.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismevalles.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/turismevalles.com\/en\/#organization","name":"Turisme Vall\u00e8s","url":"https:\/\/turismevalles.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png","contentUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png","width":314,"height":85,"caption":"Turisme Vall\u00e8s"},"image":{"@id":"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false],"thumbnail":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false],"medium":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false],"medium_large":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false],"large":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false],"thumblist":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false],"meccarouselthumb":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false],"gridsquare":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false],"tileview":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false],"1536x1536":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false],"2048x2048":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/03\/Les-Franqueses.jpg",116,121,false]},"uagb_author_info":{"display_name":"Turisme Valles","author_link":"https:\/\/turismevalles.com\/es\/author\/turismevallesoriental\/"},"uagb_comment_info":0,"uagb_excerpt":"Fiesta de San Antonio. Tres Tombs D\u00eda y hora:\u00a0domingo 07\/04\/2024 9.30 h\u00a0Almorzar de arrieros y concentraci\u00f3n de los participantes en el paseo Tagamanent. 11 h\u00a0Oficio ... Veure m\u00e9s","_links":{"self":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec-events\/54587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/comments?post=54587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/media\/54407"}],"wp:attachment":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/media?parent=54587"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/tags?post=54587"},{"taxonomy":"poblacions","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/poblacions?post=54587"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec_category?post=54587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}