{"id":55297,"date":"2024-04-16T11:06:07","date_gmt":"2024-04-16T09:06:07","guid":{"rendered":"http:\/\/turismevalles.com.mialias.net\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/"},"modified":"2024-04-16T11:07:25","modified_gmt":"2024-04-16T09:07:25","slug":"6a-trobada-de-cotxes-classics-a-llinars-del-valles","status":"publish","type":"mec-events","link":"https:\/\/turismevalles.com\/es\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/","title":{"rendered":"6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s"},"content":{"rendered":"<p>Domingo, 5 de mayo<br \/>\n6.\u00aa ENCUENTRO DE COCHES CL\u00c1SICOS<\/p>\n<p>Almuerzo gratuito por el conductor\/a<br \/>\nInscripciones de 8 a 9 h en la calle Frederic Mar\u00e9s<\/p>\n<p>Acompanyant 5 \u20ac<br \/>\nOrganiza: Moto Cl\u00e1sico Llinars<\/p>\n<p>&nbsp;<\/p>\n<p>Info:<a href=\"https:\/\/www.llinarsdelvalles.cat\/media\/repository\/diptics-triptics-cartells\/2024\/Cultura\/Agendes_d_activitats\/abrilMaigweb2024.pdf\">https:\/\/www.llinarsdelvalles.cat\/media\/repository\/diptics-triptics-cartells\/2024\/Cultura\/Agendes_d_activitats\/abrilMaigweb2024.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domingo, 5 de mayo 6.\u00aa ENCUENTRO DE COCHES CL\u00c1SICOS Almuerzo gratuito por el conductor\/a Inscripciones de 8 a 9 h en la calle Frederic Mar\u00e9s &#8230; <a title=\"6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s\" class=\"read-more\" href=\"https:\/\/turismevalles.com\/es\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/\" aria-label=\"M\u00e1s en 6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s\">Veure m\u00e9s<\/a><\/p>\n","protected":false},"author":5,"featured_media":55280,"comment_status":"open","ping_status":"closed","template":"","tags":[2115],"poblacions":[897],"mec_category":[970,1660],"class_list":["post-55297","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-cotxes-classics-es","poblacions-llinars-del-valles-es","mec_category-activitats-en-familia-es","mec_category-fires-i-festes-es","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s - Turisme Vall\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s - Turisme Vall\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Domingo, 5 de mayo 6.\u00aa ENCUENTRO DE COCHES CL\u00c1SICOS Almuerzo gratuito por el conductor\/a Inscripciones de 8 a 9 h en la calle Frederic Mar\u00e9s ... Veure m\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/\" \/>\n<meta property=\"og:site_name\" content=\"Turisme Vall\u00e8s\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-16T09:07:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"135\" \/>\n\t<meta property=\"og:image:height\" content=\"45\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/\",\"url\":\"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/\",\"name\":\"6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s - Turisme Vall\u00e8s\",\"isPartOf\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg\",\"datePublished\":\"2024-04-16T09:06:07+00:00\",\"dateModified\":\"2024-04-16T09:07:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/#primaryimage\",\"url\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg\",\"contentUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg\",\"width\":135,\"height\":45},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/turismevalles.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\/\/turismevalles.com\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turismevalles.com\/en\/#website\",\"url\":\"https:\/\/turismevalles.com\/en\/\",\"name\":\"Turisme Vall\u00e8s\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turismevalles.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/turismevalles.com\/en\/#organization\",\"name\":\"Turisme Vall\u00e8s\",\"url\":\"https:\/\/turismevalles.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png\",\"contentUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png\",\"width\":314,\"height\":85,\"caption\":\"Turisme Vall\u00e8s\"},\"image\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s - Turisme Vall\u00e8s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/","og_locale":"es_ES","og_type":"article","og_title":"6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s - Turisme Vall\u00e8s","og_description":"Domingo, 5 de mayo 6.\u00aa ENCUENTRO DE COCHES CL\u00c1SICOS Almuerzo gratuito por el conductor\/a Inscripciones de 8 a 9 h en la calle Frederic Mar\u00e9s ... Veure m\u00e9s","og_url":"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/","og_site_name":"Turisme Vall\u00e8s","article_modified_time":"2024-04-16T09:07:25+00:00","og_image":[{"width":135,"height":45,"url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/","url":"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/","name":"6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s - Turisme Vall\u00e8s","isPartOf":{"@id":"https:\/\/turismevalles.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/#primaryimage"},"image":{"@id":"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/#primaryimage"},"thumbnailUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg","datePublished":"2024-04-16T09:06:07+00:00","dateModified":"2024-04-16T09:07:25+00:00","breadcrumb":{"@id":"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/#primaryimage","url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg","contentUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg","width":135,"height":45},{"@type":"BreadcrumbList","@id":"https:\/\/turismevalles.com\/events\/6a-trobada-de-cotxes-classics-a-llinars-del-valles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/turismevalles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/turismevalles.com\/events\/"},{"@type":"ListItem","position":3,"name":"6o. Encuentro de Coches Cl\u00e1sicos en Llinars del Vall\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/turismevalles.com\/en\/#website","url":"https:\/\/turismevalles.com\/en\/","name":"Turisme Vall\u00e8s","description":"","publisher":{"@id":"https:\/\/turismevalles.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismevalles.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/turismevalles.com\/en\/#organization","name":"Turisme Vall\u00e8s","url":"https:\/\/turismevalles.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png","contentUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png","width":314,"height":85,"caption":"Turisme Vall\u00e8s"},"image":{"@id":"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false],"thumbnail":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false],"medium":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false],"medium_large":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false],"large":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false],"thumblist":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false],"meccarouselthumb":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false],"gridsquare":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false],"tileview":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false],"1536x1536":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false],"2048x2048":["https:\/\/turismevalles.com\/wp-content\/uploads\/2024\/04\/Llinars.jpg",135,45,false]},"uagb_author_info":{"display_name":"Turisme Valles","author_link":"https:\/\/turismevalles.com\/es\/author\/turismevallesoriental\/"},"uagb_comment_info":0,"uagb_excerpt":"Domingo, 5 de mayo 6.\u00aa ENCUENTRO DE COCHES CL\u00c1SICOS Almuerzo gratuito por el conductor\/a Inscripciones de 8 a 9 h en la calle Frederic Mar\u00e9s ... Veure m\u00e9s","_links":{"self":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec-events\/55297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/comments?post=55297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/media\/55280"}],"wp:attachment":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/media?parent=55297"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/tags?post=55297"},{"taxonomy":"poblacions","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/poblacions?post=55297"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec_category?post=55297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}