{"id":69835,"date":"2026-04-16T13:28:44","date_gmt":"2026-04-16T11:28:44","guid":{"rendered":"https:\/\/turismevalles.com\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/"},"modified":"2026-04-16T13:29:49","modified_gmt":"2026-04-16T11:29:49","slug":"actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui","status":"publish","type":"mec-events","link":"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/","title":{"rendered":"Actividades para todos en el Sant Jordi 2026 de Caldes de Montbui"},"content":{"rendered":"<p><a href=\"https:\/\/caldescultura.cat\/\">M\u00e1s informaci\u00f3n, aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s informaci\u00f3n, aqu\u00ed<\/p>\n","protected":false},"author":5,"featured_media":69834,"comment_status":"open","ping_status":"closed","template":"","tags":[1158,1039,3165,3156,2385,1135,2387,2050],"poblacions":[428],"mec_category":[970,929,3155,3159],"class_list":["post-69835","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-activitats-en-familia-es","tag-cultura-es","tag-letras","tag-libros-y-rosas","tag-llibres-es","tag-musica-es","tag-sant-jordi-es","tag-valles-oriental-es","poblacions-cardedeu-es","mec_category-activitats-en-familia-es","mec_category-cultura-es","mec_category-libros-y-rosas","mec_category-sant-jordi-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Actividades para todos en el Sant Jordi 2026 de Caldes de Montbui - Turisme Vall\u00e8s<\/title>\n<meta name=\"description\" content=\"Sant-Jordi-2026-en-Caldes-de-Montbui-libros-rosas-celebracion-costa-barcelona-valles-oriental-barcelona-es-mucho-mes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actividades para todos en el Sant Jordi 2026 de Caldes de Montbui - Turisme Vall\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Sant-Jordi-2026-en-Caldes-de-Montbui-libros-rosas-celebracion-costa-barcelona-valles-oriental-barcelona-es-mucho-mes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/\" \/>\n<meta property=\"og:site_name\" content=\"Turisme Vall\u00e8s\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T11:29:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/\",\"url\":\"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/\",\"name\":\"Actividades para todos en el Sant Jordi 2026 de Caldes de Montbui - Turisme Vall\u00e8s\",\"isPartOf\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png\",\"datePublished\":\"2026-04-16T11:28:44+00:00\",\"dateModified\":\"2026-04-16T11:29:49+00:00\",\"description\":\"Sant-Jordi-2026-en-Caldes-de-Montbui-libros-rosas-celebracion-costa-barcelona-valles-oriental-barcelona-es-mucho-mes\",\"breadcrumb\":{\"@id\":\"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/#primaryimage\",\"url\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png\",\"contentUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/turismevalles.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\/\/turismevalles.com\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Actividades para todos en el Sant Jordi 2026 de Caldes de Montbui\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turismevalles.com\/en\/#website\",\"url\":\"https:\/\/turismevalles.com\/en\/\",\"name\":\"Turisme Vall\u00e8s\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turismevalles.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/turismevalles.com\/en\/#organization\",\"name\":\"Turisme Vall\u00e8s\",\"url\":\"https:\/\/turismevalles.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png\",\"contentUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png\",\"width\":314,\"height\":85,\"caption\":\"Turisme Vall\u00e8s\"},\"image\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actividades para todos en el Sant Jordi 2026 de Caldes de Montbui - Turisme Vall\u00e8s","description":"Sant-Jordi-2026-en-Caldes-de-Montbui-libros-rosas-celebracion-costa-barcelona-valles-oriental-barcelona-es-mucho-mes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/","og_locale":"es_ES","og_type":"article","og_title":"Actividades para todos en el Sant Jordi 2026 de Caldes de Montbui - Turisme Vall\u00e8s","og_description":"Sant-Jordi-2026-en-Caldes-de-Montbui-libros-rosas-celebracion-costa-barcelona-valles-oriental-barcelona-es-mucho-mes","og_url":"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/","og_site_name":"Turisme Vall\u00e8s","article_modified_time":"2026-04-16T11:29:49+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/","url":"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/","name":"Actividades para todos en el Sant Jordi 2026 de Caldes de Montbui - Turisme Vall\u00e8s","isPartOf":{"@id":"https:\/\/turismevalles.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/#primaryimage"},"image":{"@id":"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/#primaryimage"},"thumbnailUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png","datePublished":"2026-04-16T11:28:44+00:00","dateModified":"2026-04-16T11:29:49+00:00","description":"Sant-Jordi-2026-en-Caldes-de-Montbui-libros-rosas-celebracion-costa-barcelona-valles-oriental-barcelona-es-mucho-mes","breadcrumb":{"@id":"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/#primaryimage","url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png","contentUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/turismevalles.com\/es\/events\/actividades-para-todos-en-el-sant-jordi-2026-de-caldes-de-montbui\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/turismevalles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/turismevalles.com\/events\/"},{"@type":"ListItem","position":3,"name":"Actividades para todos en el Sant Jordi 2026 de Caldes de Montbui"}]},{"@type":"WebSite","@id":"https:\/\/turismevalles.com\/en\/#website","url":"https:\/\/turismevalles.com\/en\/","name":"Turisme Vall\u00e8s","description":"","publisher":{"@id":"https:\/\/turismevalles.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismevalles.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/turismevalles.com\/en\/#organization","name":"Turisme Vall\u00e8s","url":"https:\/\/turismevalles.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png","contentUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png","width":314,"height":85,"caption":"Turisme Vall\u00e8s"},"image":{"@id":"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png",1280,720,false],"thumbnail":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes-150x150.png",150,150,true],"medium":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes-300x169.png",300,169,true],"medium_large":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes-768x432.png",768,432,true],"large":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes-1024x576.png",1024,576,true],"thumblist":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes-300x300.png",300,300,true],"meccarouselthumb":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes-474x324.png",474,324,true],"gridsquare":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes-391x260.png",391,260,true],"tileview":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes-300x400.png",300,400,true],"1536x1536":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png",1280,720,false],"2048x2048":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/23042026_santjordi_caldes.png",1280,720,false]},"uagb_author_info":{"display_name":"Turisme Valles","author_link":"https:\/\/turismevalles.com\/es\/author\/turismevallesoriental\/"},"uagb_comment_info":0,"uagb_excerpt":"M\u00e1s informaci\u00f3n, aqu\u00ed","_links":{"self":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec-events\/69835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/comments?post=69835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/media\/69834"}],"wp:attachment":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/media?parent=69835"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/tags?post=69835"},{"taxonomy":"poblacions","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/poblacions?post=69835"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec_category?post=69835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}