{"id":69903,"date":"2026-04-20T12:28:41","date_gmt":"2026-04-20T10:28:41","guid":{"rendered":"https:\/\/turismevalles.com\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/"},"modified":"2026-04-20T12:31:02","modified_gmt":"2026-04-20T10:31:02","slug":"celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles","status":"publish","type":"mec-events","link":"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/","title":{"rendered":"Celebraci\u00f3n de Sant Jordi con actividades para todos los p\u00fablicos en la Roca del Vall\u00e8s"},"content":{"rendered":"<p>El municipio vivir\u00e1 una celebraci\u00f3n con propuestas culturales, familiares y tradicionales repartidas entre la Roca, la Torreta i Santa Agn\u00e8s.<\/p>\n<p>Consultad la programaci\u00f3n <a href=\"http:\/\/www.laroca.cat\/actualitat\/que-esta-passant\/noticies\/la-roca-del-valles-celebra-sant-jordi-amb-una-programacio-plena-dactivitats-per-a-tots-els-publics\">aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El municipio vivir\u00e1 una celebraci\u00f3n con propuestas culturales, familiares y tradicionales repartidas entre la Roca, la Torreta i Santa Agn\u00e8s. Consultad la programaci\u00f3n aqu\u00ed<\/p>\n","protected":false},"author":5,"featured_media":69902,"comment_status":"open","ping_status":"closed","template":"","tags":[1158,1039,956,3165,3156,2385,2387,2050],"poblacions":[428],"mec_category":[970,929,3155,3159],"class_list":["post-69903","mec-events","type-mec-events","status-publish","has-post-thumbnail","hentry","tag-activitats-en-familia-es","tag-cultura-es","tag-fira-es","tag-letras","tag-libros-y-rosas","tag-llibres-es","tag-sant-jordi-es","tag-valles-oriental-es","poblacions-cardedeu-es","mec_category-activitats-en-familia-es","mec_category-cultura-es","mec_category-libros-y-rosas","mec_category-sant-jordi-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Celebraci\u00f3n de Sant Jordi con actividades para todos los p\u00fablicos en la Roca del Vall\u00e8s - Turisme Vall\u00e8s<\/title>\n<meta name=\"description\" content=\"Celebraci\u00f3n-de-Sant-Jordi-con-actividades-para-todos-los-p\u00fablicos-en-la-Roca-del-Vall\u00e8s-libros-rosas-la-torreta-santa-agn\u00e8s-costa-barcelona-valles-oriental-barcelona-es-mucho-mas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebraci\u00f3n de Sant Jordi con actividades para todos los p\u00fablicos en la Roca del Vall\u00e8s - Turisme Vall\u00e8s\" \/>\n<meta property=\"og:description\" content=\"Celebraci\u00f3n-de-Sant-Jordi-con-actividades-para-todos-los-p\u00fablicos-en-la-Roca-del-Vall\u00e8s-libros-rosas-la-torreta-santa-agn\u00e8s-costa-barcelona-valles-oriental-barcelona-es-mucho-mas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/\" \/>\n<meta property=\"og:site_name\" content=\"Turisme Vall\u00e8s\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T10:31:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"745\" \/>\n\t<meta property=\"og:image:height\" content=\"1053\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/\",\"url\":\"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/\",\"name\":\"Celebraci\u00f3n de Sant Jordi con actividades para todos los p\u00fablicos en la Roca del Vall\u00e8s - Turisme Vall\u00e8s\",\"isPartOf\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png\",\"datePublished\":\"2026-04-20T10:28:41+00:00\",\"dateModified\":\"2026-04-20T10:31:02+00:00\",\"description\":\"Celebraci\u00f3n-de-Sant-Jordi-con-actividades-para-todos-los-p\u00fablicos-en-la-Roca-del-Vall\u00e8s-libros-rosas-la-torreta-santa-agn\u00e8s-costa-barcelona-valles-oriental-barcelona-es-mucho-mas\",\"breadcrumb\":{\"@id\":\"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/#primaryimage\",\"url\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png\",\"contentUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png\",\"width\":745,\"height\":1053},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/turismevalles.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\/\/turismevalles.com\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Celebraci\u00f3n de Sant Jordi con actividades para todos los p\u00fablicos en la Roca del Vall\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turismevalles.com\/en\/#website\",\"url\":\"https:\/\/turismevalles.com\/en\/\",\"name\":\"Turisme Vall\u00e8s\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turismevalles.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/turismevalles.com\/en\/#organization\",\"name\":\"Turisme Vall\u00e8s\",\"url\":\"https:\/\/turismevalles.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png\",\"contentUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png\",\"width\":314,\"height\":85,\"caption\":\"Turisme Vall\u00e8s\"},\"image\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebraci\u00f3n de Sant Jordi con actividades para todos los p\u00fablicos en la Roca del Vall\u00e8s - Turisme Vall\u00e8s","description":"Celebraci\u00f3n-de-Sant-Jordi-con-actividades-para-todos-los-p\u00fablicos-en-la-Roca-del-Vall\u00e8s-libros-rosas-la-torreta-santa-agn\u00e8s-costa-barcelona-valles-oriental-barcelona-es-mucho-mas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/","og_locale":"es_ES","og_type":"article","og_title":"Celebraci\u00f3n de Sant Jordi con actividades para todos los p\u00fablicos en la Roca del Vall\u00e8s - Turisme Vall\u00e8s","og_description":"Celebraci\u00f3n-de-Sant-Jordi-con-actividades-para-todos-los-p\u00fablicos-en-la-Roca-del-Vall\u00e8s-libros-rosas-la-torreta-santa-agn\u00e8s-costa-barcelona-valles-oriental-barcelona-es-mucho-mas","og_url":"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/","og_site_name":"Turisme Vall\u00e8s","article_modified_time":"2026-04-20T10:31:02+00:00","og_image":[{"width":745,"height":1053,"url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/","url":"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/","name":"Celebraci\u00f3n de Sant Jordi con actividades para todos los p\u00fablicos en la Roca del Vall\u00e8s - Turisme Vall\u00e8s","isPartOf":{"@id":"https:\/\/turismevalles.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/#primaryimage"},"image":{"@id":"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/#primaryimage"},"thumbnailUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png","datePublished":"2026-04-20T10:28:41+00:00","dateModified":"2026-04-20T10:31:02+00:00","description":"Celebraci\u00f3n-de-Sant-Jordi-con-actividades-para-todos-los-p\u00fablicos-en-la-Roca-del-Vall\u00e8s-libros-rosas-la-torreta-santa-agn\u00e8s-costa-barcelona-valles-oriental-barcelona-es-mucho-mas","breadcrumb":{"@id":"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/#primaryimage","url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png","contentUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png","width":745,"height":1053},{"@type":"BreadcrumbList","@id":"https:\/\/turismevalles.com\/es\/events\/celebracion-de-sant-jordi-con-actividades-para-todos-los-publicos-en-la-roca-del-valles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/turismevalles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/turismevalles.com\/events\/"},{"@type":"ListItem","position":3,"name":"Celebraci\u00f3n de Sant Jordi con actividades para todos los p\u00fablicos en la Roca del Vall\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/turismevalles.com\/en\/#website","url":"https:\/\/turismevalles.com\/en\/","name":"Turisme Vall\u00e8s","description":"","publisher":{"@id":"https:\/\/turismevalles.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismevalles.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/turismevalles.com\/en\/#organization","name":"Turisme Vall\u00e8s","url":"https:\/\/turismevalles.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png","contentUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png","width":314,"height":85,"caption":"Turisme Vall\u00e8s"},"image":{"@id":"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png",745,1053,false],"thumbnail":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026-150x150.png",150,150,true],"medium":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026-212x300.png",212,300,true],"medium_large":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png",745,1053,false],"large":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026-724x1024.png",724,1024,true],"thumblist":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026-300x300.png",300,300,true],"meccarouselthumb":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026-474x324.png",474,324,true],"gridsquare":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026-391x260.png",391,260,true],"tileview":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026-300x400.png",300,400,true],"1536x1536":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png",745,1053,false],"2048x2048":["https:\/\/turismevalles.com\/wp-content\/uploads\/2026\/04\/SantJordiLaRoca2026.png",745,1053,false]},"uagb_author_info":{"display_name":"Turisme Valles","author_link":"https:\/\/turismevalles.com\/es\/author\/turismevallesoriental\/"},"uagb_comment_info":0,"uagb_excerpt":"El municipio vivir\u00e1 una celebraci\u00f3n con propuestas culturales, familiares y tradicionales repartidas entre la Roca, la Torreta i Santa Agn\u00e8s. Consultad la programaci\u00f3n aqu\u00ed","_links":{"self":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec-events\/69903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/comments?post=69903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/media\/69902"}],"wp:attachment":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/media?parent=69903"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/tags?post=69903"},{"taxonomy":"poblacions","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/poblacions?post=69903"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec_category?post=69903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}