{"id":2115,"count":1,"description":"","link":"https:\/\/turismevalles.com\/es\/tag\/cotxes-classics-es\/","name":"cotxes classics","slug":"cotxes-classics-es","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arxius de cotxes classics - Turisme Vall\u00e8s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/turismevalles.com\/tag\/cotxes-classics\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arxius de cotxes classics - Turisme Vall\u00e8s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/turismevalles.com\/tag\/cotxes-classics\/\" \/>\n<meta property=\"og:site_name\" content=\"Turisme Vall\u00e8s\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/turismevalles.com\/tag\/cotxes-classics\/\",\"url\":\"https:\/\/turismevalles.com\/tag\/cotxes-classics\/\",\"name\":\"Arxius de cotxes classics - Turisme Vall\u00e8s\",\"isPartOf\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/turismevalles.com\/tag\/cotxes-classics\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/turismevalles.com\/tag\/cotxes-classics\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/turismevalles.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cotxes classics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/turismevalles.com\/en\/#website\",\"url\":\"https:\/\/turismevalles.com\/en\/\",\"name\":\"Turisme Vall\u00e8s\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/turismevalles.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/turismevalles.com\/en\/#organization\",\"name\":\"Turisme Vall\u00e8s\",\"url\":\"https:\/\/turismevalles.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png\",\"contentUrl\":\"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png\",\"width\":314,\"height\":85,\"caption\":\"Turisme Vall\u00e8s\"},\"image\":{\"@id\":\"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arxius de cotxes classics - Turisme Vall\u00e8s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/turismevalles.com\/tag\/cotxes-classics\/","og_locale":"es_ES","og_type":"article","og_title":"Arxius de cotxes classics - Turisme Vall\u00e8s","og_url":"https:\/\/turismevalles.com\/tag\/cotxes-classics\/","og_site_name":"Turisme Vall\u00e8s","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/turismevalles.com\/tag\/cotxes-classics\/","url":"https:\/\/turismevalles.com\/tag\/cotxes-classics\/","name":"Arxius de cotxes classics - Turisme Vall\u00e8s","isPartOf":{"@id":"https:\/\/turismevalles.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/turismevalles.com\/tag\/cotxes-classics\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/turismevalles.com\/tag\/cotxes-classics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/turismevalles.com\/es\/"},{"@type":"ListItem","position":2,"name":"cotxes classics"}]},{"@type":"WebSite","@id":"https:\/\/turismevalles.com\/en\/#website","url":"https:\/\/turismevalles.com\/en\/","name":"Turisme Vall\u00e8s","description":"","publisher":{"@id":"https:\/\/turismevalles.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/turismevalles.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/turismevalles.com\/en\/#organization","name":"Turisme Vall\u00e8s","url":"https:\/\/turismevalles.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png","contentUrl":"https:\/\/turismevalles.com\/wp-content\/uploads\/2020\/08\/cropped-logo_ca-2.png","width":314,"height":85,"caption":"Turisme Vall\u00e8s"},"image":{"@id":"https:\/\/turismevalles.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/tags\/2115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/posts?tags=2115"},{"href":"https:\/\/turismevalles.com\/es\/wp-json\/wp\/v2\/mec-events?tags=2115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}